{"id":514,"date":"2026-02-13T14:31:34","date_gmt":"2026-02-13T14:31:34","guid":{"rendered":"https:\/\/cidnetdev.wpengine.com\/cidnet-solutions\/?post_type=app-suite&#038;p=514"},"modified":"2026-04-30T12:05:40","modified_gmt":"2026-04-30T12:05:40","slug":"forms","status":"publish","type":"app-suite","link":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/","title":{"rendered":"Forms"},"content":{"rendered":"<style>.kb-row-layout-id514_6b1e68-2d > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id514_6b1e68-2d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id514_6b1e68-2d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, calc(70% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(30% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id514_6b1e68-2d{background-image:url('https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/background-focused-in-the-foreground-with-lines-an-2026-01-05-22-53-50-utc-1.webp');background-size:cover;background-position:49% 49%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id514_6b1e68-2d > .kt-row-layout-overlay{opacity:0.95;background:linear-gradient(90deg,rgba(0,0,0,0.8) 6%,rgba(0,0,0,0.8) 72%);}@media all and (max-width: 1024px){.kb-row-layout-id514_6b1e68-2d > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id514_6b1e68-2d > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg,rgba(0,0,0,0.8) 6%,rgba(0,0,0,0.8) 72%);}}@media all and (max-width: 767px){.kb-row-layout-id514_6b1e68-2d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id514_6b1e68-2d alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column514_a75412-9b > .kt-inside-inner-col,.kadence-column514_a75412-9b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_a75412-9b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_a75412-9b > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_a75412-9b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_a75412-9b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_a75412-9b{position:relative;}@media all and (max-width: 1024px){.kadence-column514_a75412-9b{text-align:center;}}@media all and (max-width: 1024px){.kadence-column514_a75412-9b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_a75412-9b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_a75412-9b kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading514_a565e8-77, .wp-block-kadence-advancedheading.kt-adv-heading514_a565e8-77[data-kb-block=\"kb-adv-heading514_a565e8-77\"]{margin-top:20px;text-align:left;font-size:var(--global-kb-font-size-xxl, 4rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_a565e8-77 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_a565e8-77[data-kb-block=\"kb-adv-heading514_a565e8-77\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_a565e8-77 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_a565e8-77[data-kb-block=\"kb-adv-heading514_a565e8-77\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading514_a565e8-77 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading514_a565e8-77\">The Forms App<\/h1>\n\n\n<style>.wp-block-kadence-image.kb-image514_e221af-64:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:34px;margin-bottom:24px;}.kb-image514_e221af-64 .kb-image-has-overlay:after{opacity:0.3;}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image514_e221af-64:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:24px;margin-bottom:16px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image514_e221af-64 size-large image-is-svg\" data-aos=\"fade\" data-aos-duration=\"800\" data-aos-delay=\"300\" data-aos-easing=\"linear\"><img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"18\" src=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/hexagons-3.svg\" alt=\"\" class=\"kb-img wp-image-49\"\/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e, .wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e[data-kb-block=\"kb-adv-heading514_3dfe31-3e\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);text-align:left;font-size:1.5rem;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e[data-kb-block=\"kb-adv-heading514_3dfe31-3e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e[data-kb-block=\"kb-adv-heading514_3dfe31-3e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e, .wp-block-kadence-advancedheading.kt-adv-heading514_3dfe31-3e[data-kb-block=\"kb-adv-heading514_3dfe31-3e\"]{font-size:1.25rem;}}<\/style>\n<div class=\"kt-adv-heading514_3dfe31-3e wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading514_3dfe31-3e\">Digital Forms App for Correctional Facilities<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_535e5c-ea, .wp-block-kadence-advancedheading.kt-adv-heading514_535e5c-ea[data-kb-block=\"kb-adv-heading514_535e5c-ea\"]{text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_535e5c-ea mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_535e5c-ea[data-kb-block=\"kb-adv-heading514_535e5c-ea\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_535e5c-ea img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_535e5c-ea[data-kb-block=\"kb-adv-heading514_535e5c-ea\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading514_535e5c-ea wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading514_535e5c-ea\">The Enquire App will let inmates submit jail forms and kites to custom groups of jail personnel. Every device is a direct line for inmates to submit grievances, medical requests, or any other custom jail form.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns514_f1ece3-72{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns514_f1ece3-72 .kt-button{font-weight:normal;font-style:normal;}.kt-btns514_f1ece3-72 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns514_f1ece3-72 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns514_f1ece3-72 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns514_f1ece3-72 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns514_f1ece3-72 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns514_f1ece3-72 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns514_f1ece3-72 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns514_f1ece3-72\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn514_aca37c-27.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn514_aca37c-27 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/\"><span class=\"kt-btn-inner-text\">Explore App Library<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn514_4654ca-bc.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn514_4654ca-bc kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit button-style-secondary kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/cidnet.navattic.com\/ppt?g=clrtonjur000e0gjrbmao50kv&#038;s=0\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">View Apps Demo<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column514_3f6f18-51 > .kt-inside-inner-col,.kadence-column514_3f6f18-51 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_3f6f18-51 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_3f6f18-51 > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_3f6f18-51 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_3f6f18-51 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_3f6f18-51{position:relative;}@media all and (max-width: 1024px){.kadence-column514_3f6f18-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_3f6f18-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_3f6f18-51 kvs-md-false kvs-sm-false\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id514_aba8db-65 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id514_aba8db-65 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id514_aba8db-65 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-bottom:120px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id514_aba8db-65 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id514_aba8db-65 > .kt-row-column-wrap{padding-top:60px;padding-bottom:60px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id514_aba8db-65 > .kt-row-column-wrap{padding-top:40px;padding-bottom:20px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id514_aba8db-65 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column514_7cdbd2-82 > .kt-inside-inner-col,.kadence-column514_7cdbd2-82 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_7cdbd2-82 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_7cdbd2-82 > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_7cdbd2-82 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_7cdbd2-82 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_7cdbd2-82{position:relative;}@media all and (max-width: 1024px){.kadence-column514_7cdbd2-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_7cdbd2-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_7cdbd2-82\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id514_5eabb0-20 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id514_5eabb0-20 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id514_5eabb0-20 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id514_5eabb0-20 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id514_5eabb0-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id514_5eabb0-20 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id514_5eabb0-20 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{display:flex;}#wrapper.site{overflow:clip;}.kadence-column514_a6fa0e-07{--kb-section-setting-offset:160px;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col,.kadence-column514_a6fa0e-07 > .kt-inside-inner-col:before{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-end;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column514_a6fa0e-07{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_a6fa0e-07{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{background-image:url('https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_27_CO-Inmate-Forms-e1657054037371.webp');background-size:cover;background-position:33% 61%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col:before{opacity:0.46;background-image:url('https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/hex4.webp');background-size:25% auto;background-position:0% 0%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column514_a6fa0e-07{position:relative;}@media all and (max-width: 1024px){.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{min-height:400px;flex-direction:column;justify-content:center;align-items:flex-end;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column514_a6fa0e-07{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_a6fa0e-07{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column514_a6fa0e-07{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_a6fa0e-07{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column514_a6fa0e-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-end;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_a6fa0e-07 kb-section-is-sticky kb-section-has-overlay\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column514_35df5c-58 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);}.kadence-column514_35df5c-58 > .kt-inside-inner-col,.kadence-column514_35df5c-58 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_35df5c-58 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_35df5c-58 > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_35df5c-58 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_35df5c-58 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_35df5c-58, .kadence-column514_35df5c-58 h1, .kadence-column514_35df5c-58 h2, .kadence-column514_35df5c-58 h3, .kadence-column514_35df5c-58 h4, .kadence-column514_35df5c-58 h5, .kadence-column514_35df5c-58 h6{color:var(--global-palette4, #2D3748);}.kadence-column514_35df5c-58{position:relative;}@media all and (max-width: 1024px){.kadence-column514_35df5c-58 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_35df5c-58 > .kt-inside-inner-col{padding-top:0px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_35df5c-58\"><div class=\"kt-inside-inner-col\"><style>.kadence-column514_a11725-8e > .kt-inside-inner-col{padding-top:0px;}.kadence-column514_a11725-8e > .kt-inside-inner-col,.kadence-column514_a11725-8e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_a11725-8e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_a11725-8e > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_a11725-8e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_a11725-8e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_a11725-8e{position:relative;}@media all and (max-width: 1024px){.kadence-column514_a11725-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_a11725-8e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_a11725-8e\" data-aos=\"fade-up\" data-aos-duration=\"2000\"><div class=\"kt-inside-inner-col\"><style>.kb-image514_63fb30-80.kb-image-is-ratio-size, .kb-image514_63fb30-80 .kb-image-is-ratio-size{max-width:85px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image514_63fb30-80.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image514_63fb30-80 .kb-image-is-ratio-size{align-self:unset;}.kb-image514_63fb30-80{max-width:85px;}.image-is-svg.kb-image514_63fb30-80{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image514_63fb30-80 img{width:100%;}.kb-image514_63fb30-80 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image514_63fb30-80 size-large image-is-svg\"><img loading=\"lazy\" decoding=\"async\" width=\"146\" height=\"164\" src=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/download-2-2.svg\" alt=\"\" class=\"kb-img wp-image-1011\"\/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_f4b814-a4, .wp-block-kadence-advancedheading.kt-adv-heading514_f4b814-a4[data-kb-block=\"kb-adv-heading514_f4b814-a4\"]{margin-top:0px;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading514_f4b814-a4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_f4b814-a4[data-kb-block=\"kb-adv-heading514_f4b814-a4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_f4b814-a4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_f4b814-a4[data-kb-block=\"kb-adv-heading514_f4b814-a4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading514_f4b814-a4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading514_f4b814-a4\"><strong>Submission Certainty<\/strong><\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_080a15-8a, .wp-block-kadence-advancedheading.kt-adv-heading514_080a15-8a[data-kb-block=\"kb-adv-heading514_080a15-8a\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_080a15-8a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_080a15-8a[data-kb-block=\"kb-adv-heading514_080a15-8a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_080a15-8a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_080a15-8a[data-kb-block=\"kb-adv-heading514_080a15-8a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading514_080a15-8a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading514_080a15-8a\">As soon as an inmate submits a form, Cidnet immediately takes and uploads a picture of the submitter for Face ID verification. At all stages of the process, inmates can see the status of their request. Enquire also enables staff and inmates to message back and forth about the inmate\u2019s request or grievance, creating a more responsive approach to form submission.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-3xl, 6.5rem);}.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col,.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_6f3d3d-e9{position:relative;}@media all and (max-width: 1024px){.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_6f3d3d-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_6f3d3d-e9\" data-aos=\"fade-up\" data-aos-duration=\"2000\"><div class=\"kt-inside-inner-col\"><style>.kb-image514_91881d-0b.kb-image-is-ratio-size, .kb-image514_91881d-0b .kb-image-is-ratio-size{max-width:85px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image514_91881d-0b.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image514_91881d-0b .kb-image-is-ratio-size{align-self:unset;}.kb-image514_91881d-0b{max-width:85px;}.image-is-svg.kb-image514_91881d-0b{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image514_91881d-0b img{width:100%;}.kb-image514_91881d-0b .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image514_91881d-0b size-large image-is-svg\"><img loading=\"lazy\" decoding=\"async\" width=\"146\" height=\"164\" src=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/download-1-2.svg\" alt=\"\" class=\"kb-img wp-image-1012\"\/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_f27e4e-21, .wp-block-kadence-advancedheading.kt-adv-heading514_f27e4e-21[data-kb-block=\"kb-adv-heading514_f27e4e-21\"]{margin-top:0px;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading514_f27e4e-21 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_f27e4e-21[data-kb-block=\"kb-adv-heading514_f27e4e-21\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_f27e4e-21 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_f27e4e-21[data-kb-block=\"kb-adv-heading514_f27e4e-21\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading514_f27e4e-21 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading514_f27e4e-21\">Expedite the Process<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_f97f1f-72, .wp-block-kadence-advancedheading.kt-adv-heading514_f97f1f-72[data-kb-block=\"kb-adv-heading514_f97f1f-72\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_f97f1f-72 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_f97f1f-72[data-kb-block=\"kb-adv-heading514_f97f1f-72\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_f97f1f-72 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_f97f1f-72[data-kb-block=\"kb-adv-heading514_f97f1f-72\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading514_f97f1f-72 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading514_f97f1f-72\">We\u2019ve built specialized quick-process screens to shrink the amount of time and effort that goes into inmate form fulfillment\/review. Complete, deny, and respond to a form in seconds\u2014all from the comfort of your desk or smart phone. Enquire also allows staff to build forms or edit existing ones to ensure they\u2019re customized for your facility.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column514_e1f389-6e > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-3xl, 6.5rem);}.kadence-column514_e1f389-6e > .kt-inside-inner-col,.kadence-column514_e1f389-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_e1f389-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_e1f389-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_e1f389-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_e1f389-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_e1f389-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column514_e1f389-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_e1f389-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_e1f389-6e\" data-aos=\"fade-up\" data-aos-duration=\"2000\"><div class=\"kt-inside-inner-col\"><style>.kb-image514_cfd68a-c0.kb-image-is-ratio-size, .kb-image514_cfd68a-c0 .kb-image-is-ratio-size{max-width:85px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image514_cfd68a-c0.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image514_cfd68a-c0 .kb-image-is-ratio-size{align-self:unset;}.kb-image514_cfd68a-c0{max-width:85px;}.image-is-svg.kb-image514_cfd68a-c0{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image514_cfd68a-c0 img{width:100%;}.kb-image514_cfd68a-c0 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image514_cfd68a-c0 size-large image-is-svg\"><img loading=\"lazy\" decoding=\"async\" width=\"146\" height=\"164\" src=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/download-4.svg\" alt=\"\" class=\"kb-img wp-image-1013\"\/><\/figure>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_b0b25f-55, .wp-block-kadence-advancedheading.kt-adv-heading514_b0b25f-55[data-kb-block=\"kb-adv-heading514_b0b25f-55\"]{margin-top:0px;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading514_b0b25f-55 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_b0b25f-55[data-kb-block=\"kb-adv-heading514_b0b25f-55\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_b0b25f-55 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_b0b25f-55[data-kb-block=\"kb-adv-heading514_b0b25f-55\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading514_b0b25f-55 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading514_b0b25f-55\">Robust Reporting<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_2253ab-fd, .wp-block-kadence-advancedheading.kt-adv-heading514_2253ab-fd[data-kb-block=\"kb-adv-heading514_2253ab-fd\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_2253ab-fd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_2253ab-fd[data-kb-block=\"kb-adv-heading514_2253ab-fd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_2253ab-fd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_2253ab-fd[data-kb-block=\"kb-adv-heading514_2253ab-fd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading514_2253ab-fd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading514_2253ab-fd\">Cidnet makes it easy to organize Enquire forms into electronically manageable reports, cutting out the need for paper. Once a report is generated, it can be downloaded into a pdf format and exported so jail personnel can keep a record of all form submissions.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<style>.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id514_90d5fe-89 > .kt-row-layout-overlay{opacity:1;}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id514_90d5fe-89 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id514_90d5fe-89 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column514_997ec0-80 > .kt-inside-inner-col{display:flex;}.kadence-column514_997ec0-80 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);}.kadence-column514_997ec0-80 > .kt-inside-inner-col{min-height:500px;}.kadence-column514_997ec0-80 > .kt-inside-inner-col,.kadence-column514_997ec0-80 > .kt-inside-inner-col:before{border-top-left-radius:3px;border-top-right-radius:3px;border-bottom-right-radius:3px;border-bottom-left-radius:3px;}.kadence-column514_997ec0-80 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_997ec0-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column514_997ec0-80 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column514_997ec0-80{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_997ec0-80{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_997ec0-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column514_997ec0-80 > .kt-inside-inner-col{background-color:var(--global-palette1, #3182CE);}.kadence-column514_997ec0-80:hover > .kt-inside-inner-col{background-image:linear-gradient(135deg,var(--global-palette1) 22%,var(--global-palette10) 100%);}.kadence-column514_997ec0-80 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_997ec0-80{z-index:100;position:relative;}.kadence-column514_997ec0-80, .kt-inside-inner-col > .kadence-column514_997ec0-80:not(.specificity){margin-right:-90px;margin-left:50px;}@media all and (max-width: 1024px){.kadence-column514_997ec0-80 > .kt-inside-inner-col{padding-right:0px;min-height:300px;flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column514_997ec0-80{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_997ec0-80{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_997ec0-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column514_997ec0-80{text-align:center;}}@media all and (max-width: 1024px){.kadence-column514_997ec0-80, .kt-inside-inner-col > .kadence-column514_997ec0-80:not(.specificity){margin-top:0px;margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column514_997ec0-80 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);min-height:300px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column514_997ec0-80{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_997ec0-80{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column514_997ec0-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column514_997ec0-80, .kt-inside-inner-col > .kadence-column514_997ec0-80:not(.specificity){margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_997ec0-80 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28, .wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28[data-kb-block=\"kb-adv-heading514_f3c294-28\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-md, 2rem);font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28[data-kb-block=\"kb-adv-heading514_f3c294-28\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28[data-kb-block=\"kb-adv-heading514_f3c294-28\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28, .wp-block-kadence-advancedheading.kt-adv-heading514_f3c294-28[data-kb-block=\"kb-adv-heading514_f3c294-28\"]{font-size:var(--global-kb-font-size-lg, 2rem);text-align:left!important;}}<\/style>\n<h1 class=\"kt-adv-heading514_f3c294-28 wp-block-kadence-advancedheading has-theme-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading514_f3c294-28\">How CID Net Forms Works<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9, .wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9[data-kb-block=\"kb-adv-heading514_55708d-b9\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9[data-kb-block=\"kb-adv-heading514_55708d-b9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9[data-kb-block=\"kb-adv-heading514_55708d-b9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9, .wp-block-kadence-advancedheading.kt-adv-heading514_55708d-b9[data-kb-block=\"kb-adv-heading514_55708d-b9\"]{text-align:left!important;}}<\/style>\n<p class=\"kt-adv-heading514_55708d-b9 wp-block-kadence-advancedheading has-theme-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading514_55708d-b9\">The CID Net Forms App lets facilities create, manage, and complete digital forms securely through the same internet-based platform used for communications and oversight. Residents, staff, or approved contacts can fill out and submit forms using a secure interface, with data flowing directly into the CID Net administrative portal.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns514_81203d-1b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns514_81203d-1b .kt-button{font-weight:normal;font-style:normal;}.kt-btns514_81203d-1b .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns514_81203d-1b .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns514_81203d-1b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns514_81203d-1b .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns514_81203d-1b .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns514_81203d-1b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns514_81203d-1b .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns514_81203d-1b\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn514_cfd0b7-e9.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn514_cfd0b7-e9 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false ktblocksvideopop wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/vimeo.com\/348684735?fl=pl&#038;fe=vl\"><span class=\"kt-btn-inner-text\">Watch Video to Learn More<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column514_b84bce-05 > .kt-inside-inner-col,.kadence-column514_b84bce-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_b84bce-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_b84bce-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_b84bce-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_b84bce-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_b84bce-05{position:relative;}@media all and (max-width: 1024px){.kadence-column514_b84bce-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_b84bce-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_b84bce-05 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image514_0312c7-a5 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;}.kb-image514_0312c7-a5 img.kb-img, .kb-image514_0312c7-a5 .kb-img img{border-top-left-radius:8px;border-top-right-radius:8px;border-bottom-right-radius:8px;border-bottom-left-radius:8px;object-position:8% 66%;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image514_0312c7-a5:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-bottom:-100px;}}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image514_0312c7-a5:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-right:0px;margin-left:0px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image514_0312c7-a5 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"599\" src=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_2_Forms-Submit.webp\" alt=\"\" class=\"kb-img wp-image-1014\" srcset=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_2_Forms-Submit.webp 900w, https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_2_Forms-Submit-300x200.webp 300w, https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_2_Forms-Submit-768x511.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id514_09c4a8-83 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id514_09c4a8-83 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id514_09c4a8-83 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id514_09c4a8-83 > .kt-row-layout-overlay{opacity:0.11;background-image:url('https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/architecture-2026-01-06-08-56-00-utc.webp');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}@media all and (max-width: 1024px){.kb-row-layout-id514_09c4a8-83 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id514_09c4a8-83 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id514_09c4a8-83 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column514_c2f481-5c > .kt-inside-inner-col,.kadence-column514_c2f481-5c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_c2f481-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_c2f481-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_c2f481-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_c2f481-5c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_c2f481-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column514_c2f481-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_c2f481-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_c2f481-5c\"><div class=\"kt-inside-inner-col\"><style>.kb-image514_d88854-02 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:16px;border-top-right-radius:16px;border-bottom-right-radius:16px;border-bottom-left-radius:16px;}.kb-image514_d88854-02 img.kb-img, .kb-image514_d88854-02 .kb-img img{border-top-left-radius:16px;border-top-right-radius:16px;border-bottom-right-radius:16px;border-bottom-left-radius:16px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image514_d88854-02 size-large\" data-aos=\"zoom-in-up\" data-aos-duration=\"2650\" data-aos-easing=\"ease-in-out-cubic\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_4_Forms-Report-1024x703.webp\" alt=\"\" class=\"kb-img wp-image-1017\" srcset=\"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_4_Forms-Report-1024x703.webp 1024w, https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_4_Forms-Report-300x206.webp 300w, https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_4_Forms-Report-768x527.webp 768w, https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/imgi_4_Forms-Report.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column514_0c9cec-d8 > .kt-inside-inner-col,.kadence-column514_0c9cec-d8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column514_0c9cec-d8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column514_0c9cec-d8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column514_0c9cec-d8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column514_0c9cec-d8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column514_0c9cec-d8{position:relative;}@media all and (max-width: 1024px){.kadence-column514_0c9cec-d8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column514_0c9cec-d8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column514_0c9cec-d8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading514_5c7366-48, .wp-block-kadence-advancedheading.kt-adv-heading514_5c7366-48[data-kb-block=\"kb-adv-heading514_5c7366-48\"]{margin-top:20px;font-size:36px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_5c7366-48 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_5c7366-48[data-kb-block=\"kb-adv-heading514_5c7366-48\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_5c7366-48 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_5c7366-48[data-kb-block=\"kb-adv-heading514_5c7366-48\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading514_5c7366-48 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading514_5c7366-48\">Secure, Centralized Form Management<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading514_0fb101-4d, .wp-block-kadence-advancedheading.kt-adv-heading514_0fb101-4d[data-kb-block=\"kb-adv-heading514_0fb101-4d\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading514_0fb101-4d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading514_0fb101-4d[data-kb-block=\"kb-adv-heading514_0fb101-4d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading514_0fb101-4d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading514_0fb101-4d[data-kb-block=\"kb-adv-heading514_0fb101-4d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading514_0fb101-4d wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading514_0fb101-4d\">Administrators can configure form templates, set conditional logic, and determine routing or approval workflows \u2014 all without paper, manual data entry, or separate systems. Submitted forms are stored, searchable, and auditable within the centralized CID Net environment, giving staff real-time visibility and reducing administrative burden.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns514_cda9f1-f9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns514_cda9f1-f9 .kt-button{font-weight:normal;font-style:normal;}.kt-btns514_cda9f1-f9 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns514_cda9f1-f9 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns514_cda9f1-f9 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns514_cda9f1-f9 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns514_cda9f1-f9 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns514_cda9f1-f9 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns514_cda9f1-f9 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns514_cda9f1-f9\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn514_6c9713-bb.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn514_6c9713-bb kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/cidnet.net\/cidnet-solutions\/request-a-demo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">Request a Demo<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id725_ffcec1-25 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id725_ffcec1-25 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id725_ffcec1-25 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id725_ffcec1-25 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id725_ffcec1-25 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id725_ffcec1-25 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id725_ffcec1-25 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column725_25e934-35 > .kt-inside-inner-col{display:flex;}.kadence-column725_25e934-35 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xl, 4rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);}.kadence-column725_25e934-35 > .kt-inside-inner-col{min-height:300px;}.kadence-column725_25e934-35 > .kt-inside-inner-col,.kadence-column725_25e934-35 > .kt-inside-inner-col:before{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kadence-column725_25e934-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column725_25e934-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column725_25e934-35 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column725_25e934-35 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column725_25e934-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column725_25e934-35{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column725_25e934-35{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column725_25e934-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column725_25e934-35 > .kt-inside-inner-col{background-color:var(--global-palette5, #4A5568);}.kadence-column725_25e934-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column725_25e934-35{z-index:100;position:relative;}@media all and (max-width: 1024px){.kadence-column725_25e934-35 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column725_25e934-35{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column725_25e934-35{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column725_25e934-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column725_25e934-35{text-align:center;}}@media all and (max-width: 767px){.kadence-column725_25e934-35 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);min-height:300px;flex-direction:column;justify-content:center;align-items:center;}.kt-row-column-wrap > .kadence-column725_25e934-35{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column725_25e934-35{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column725_25e934-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column725_25e934-35 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id725_713aeb-5c > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id725_713aeb-5c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id725_713aeb-5c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id725_713aeb-5c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id725_713aeb-5c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id725_713aeb-5c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id725_713aeb-5c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column725_384bf5-a3 > .kt-inside-inner-col,.kadence-column725_384bf5-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column725_384bf5-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column725_384bf5-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column725_384bf5-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column725_384bf5-a3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column725_384bf5-a3{position:relative;}@media all and (max-width: 1024px){.kadence-column725_384bf5-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column725_384bf5-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column725_384bf5-a3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f, .wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f[data-kb-block=\"kb-adv-heading725_7550c2-8f\"]{margin-top:0px;margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:var(--global-kb-font-size-xl, 3rem);line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f[data-kb-block=\"kb-adv-heading725_7550c2-8f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f[data-kb-block=\"kb-adv-heading725_7550c2-8f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f, .wp-block-kadence-advancedheading.kt-adv-heading725_7550c2-8f[data-kb-block=\"kb-adv-heading725_7550c2-8f\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left!important;}}<\/style>\n<h2 class=\"kt-adv-heading725_7550c2-8f wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading725_7550c2-8f\">See Cidnet in Action at Your Facility<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73, .wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73[data-kb-block=\"kb-adv-heading725_cbb235-73\"]{text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73[data-kb-block=\"kb-adv-heading725_cbb235-73\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73[data-kb-block=\"kb-adv-heading725_cbb235-73\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73, .wp-block-kadence-advancedheading.kt-adv-heading725_cbb235-73[data-kb-block=\"kb-adv-heading725_cbb235-73\"]{font-size:var(--global-kb-font-size-md, 1.25rem);text-align:left!important;}}<\/style>\n<p class=\"kt-adv-heading725_cbb235-73 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading725_cbb235-73\">Schedule a short demo to see how Cidnet helps correctional facilities manage communications, intelligence, and daily operations through one secure platform.<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items725_25630e-c2:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items725_25630e-c2 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;column-gap:30px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items725_25630e-c2 ul.kt-svg-icon-list{grid-row-gap:14px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items725_25630e-c2 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:15px;}.kt-svg-icon-list-items725_25630e-c2 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items725_25630e-c2 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:var(--global-palette9, #ffffff);font-size:var(--global-kb-font-size-md, 1.25rem);color:var(--global-palette9, #ffffff);}.kt-svg-icon-list-items725_25630e-c2 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items725_25630e-c2 kt-svg-icon-list-columns-1 aligncenter kt-list-icon-aligntop kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-725_2009a8-6f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-725_2009a8-6f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Deploy 1:1 Inmate-to-Tablet Access<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-725_b7269b-49 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-725_b7269b-49\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Lower Costs for Friends and Family<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-725_60ed32-e7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-725_60ed32-e7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Get More Reliable Customer Support<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-725_e7eb8b-79 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-725_e7eb8b-79\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Improve Facility Indoor Air Quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-725_21aee3-48 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-725_21aee3-48\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_check kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"20 6 9 17 4 12\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Streamline my Facility Policies with Signage<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns725_5f85c9-01{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns725_5f85c9-01 .kt-button{font-weight:normal;font-style:normal;}.kt-btns725_5f85c9-01 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns725_5f85c9-01 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns725_5f85c9-01 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns725_5f85c9-01 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns725_5f85c9-01 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns725_5f85c9-01 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns725_5f85c9-01 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns725_5f85c9-01\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button{color:var(--global-palette9, #ffffff);background:rgba(0,0,0,0);border-top:1px solid var(--global-palette9, #ffffff);border-right:1px solid var(--global-palette9, #ffffff);border-bottom:1px solid var(--global-palette9, #ffffff);border-left:1px solid var(--global-palette9, #ffffff);box-shadow:1px 1px 2px 3px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button{border-top:1px solid var(--global-palette9, #ffffff);border-right:1px solid var(--global-palette9, #ffffff);border-bottom:1px solid var(--global-palette9, #ffffff);border-left:1px solid var(--global-palette9, #ffffff);}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button{border-top:1px solid var(--global-palette9, #ffffff);border-right:1px solid var(--global-palette9, #ffffff);border-bottom:1px solid var(--global-palette9, #ffffff);border-left:1px solid var(--global-palette9, #ffffff);}.wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn725_78d2b6-db.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn725_78d2b6-db kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/cidnet.net\/cidnet-solutions\/request-a-demo\/\"><span class=\"kt-btn-inner-text\">Request a Demo<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":true,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"apps-suite-category":[8],"class_list":["post-514","app-suite","type-app-suite","status-publish","hentry","apps-suite-category-operations-apps"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital Forms App for Correctional Facilities - CID Net<\/title>\n<meta name=\"description\" content=\"The Forms App lets correctional facilities create, route, review, and store digital forms with searchable records and less manual processing.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital Forms App for Correctional Facilities - CID Net\" \/>\n<meta property=\"og:description\" content=\"The Forms App lets correctional facilities create, route, review, and store digital forms with searchable records and less manual processing.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/\" \/>\n<meta property=\"og:site_name\" content=\"Cidnet Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T12:05:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/\",\"url\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/\",\"name\":\"Digital Forms App for Correctional Facilities - CID Net\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/hexagons-3.svg\",\"datePublished\":\"2026-02-13T14:31:34+00:00\",\"dateModified\":\"2026-04-30T12:05:40+00:00\",\"description\":\"The Forms App lets correctional facilities create, route, review, and store digital forms with searchable records and less manual processing.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/hexagons-3.svg\",\"contentUrl\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/hexagons-3.svg\",\"width\":70,\"height\":18},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/app-suite\\\/forms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forms\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/#website\",\"url\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/\",\"name\":\"Cidnet Solutions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/#organization\",\"name\":\"Cidnet Solutions\",\"url\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/logo.svg\",\"width\":464,\"height\":141,\"caption\":\"Cidnet Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/cidnet.net\\\/cidnet-solutions\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital Forms App for Correctional Facilities - CID Net","description":"The Forms App lets correctional facilities create, route, review, and store digital forms with searchable records and less manual processing.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/","og_locale":"en_US","og_type":"article","og_title":"Digital Forms App for Correctional Facilities - CID Net","og_description":"The Forms App lets correctional facilities create, route, review, and store digital forms with searchable records and less manual processing.","og_url":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/","og_site_name":"Cidnet Solutions","article_modified_time":"2026-04-30T12:05:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/","url":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/","name":"Digital Forms App for Correctional Facilities - CID Net","isPartOf":{"@id":"https:\/\/cidnet.net\/cidnet-solutions\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/#primaryimage"},"image":{"@id":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/#primaryimage"},"thumbnailUrl":"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/hexagons-3.svg","datePublished":"2026-02-13T14:31:34+00:00","dateModified":"2026-04-30T12:05:40+00:00","description":"The Forms App lets correctional facilities create, route, review, and store digital forms with searchable records and less manual processing.","breadcrumb":{"@id":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/#primaryimage","url":"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/hexagons-3.svg","contentUrl":"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/hexagons-3.svg","width":70,"height":18},{"@type":"BreadcrumbList","@id":"https:\/\/cidnet.net\/cidnet-solutions\/app-suite\/forms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cidnet.net\/cidnet-solutions\/"},{"@type":"ListItem","position":2,"name":"Forms"}]},{"@type":"WebSite","@id":"https:\/\/cidnet.net\/cidnet-solutions\/#website","url":"https:\/\/cidnet.net\/cidnet-solutions\/","name":"Cidnet Solutions","description":"","publisher":{"@id":"https:\/\/cidnet.net\/cidnet-solutions\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cidnet.net\/cidnet-solutions\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cidnet.net\/cidnet-solutions\/#organization","name":"Cidnet Solutions","url":"https:\/\/cidnet.net\/cidnet-solutions\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cidnet.net\/cidnet-solutions\/#\/schema\/logo\/image\/","url":"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/logo.svg","contentUrl":"https:\/\/cidnet.net\/cidnet-solutions\/wp-content\/uploads\/sites\/3\/2026\/02\/logo.svg","width":464,"height":141,"caption":"Cidnet Solutions"},"image":{"@id":"https:\/\/cidnet.net\/cidnet-solutions\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"apps-suite-category":[{"value":8,"label":"Operations Apps"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/cidnet.net\/cidnet-solutions\/wp-json\/wp\/v2\/app-suite\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cidnet.net\/cidnet-solutions\/wp-json\/wp\/v2\/app-suite"}],"about":[{"href":"https:\/\/cidnet.net\/cidnet-solutions\/wp-json\/wp\/v2\/types\/app-suite"}],"wp:attachment":[{"href":"https:\/\/cidnet.net\/cidnet-solutions\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"apps-suite-category","embeddable":true,"href":"https:\/\/cidnet.net\/cidnet-solutions\/wp-json\/wp\/v2\/apps-suite-category?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}